{"id":27629,"date":"2026-05-13T07:35:00","date_gmt":"2026-05-13T10:35:00","guid":{"rendered":"https:\/\/diariodepernambuco.audiencelabs.com.br\/?p=27629"},"modified":"2026-05-12T14:36:46","modified_gmt":"2026-05-12T17:36:46","slug":"rival-da-shopee-no-brasil-surpreende-e-anuncia-fechamento-de-plataforma-especifica","status":"publish","type":"post","link":"https:\/\/diariodepernambuco.audiencelabs.com.br\/rival-da-shopee-no-brasil-surpreende-e-anuncia-fechamento-de-plataforma-especifica\/","title":{"rendered":"Rival da Shopee no Brasil surpreende e anuncia fechamento de plataforma espec\u00edfica"},"content":{"rendered":"\n<p>A Enjoei anunciou o encerramento da <strong>Elo7<\/strong>, marketplace conhecido por reunir produtos artesanais feitos por pequenos vendedores. A decis\u00e3o foi divulgada nesta segunda-feira (11) e j\u00e1 come\u00e7ou a valer no mesmo dia.<\/p>\n\n\n\n<p>O site continua dispon\u00edvel, mas n\u00e3o permite mais novas compras. Os usu\u00e1rios podem at\u00e9 acessar os produtos, por\u00e9m n\u00e3o conseguem finalizar os pedidos. Vendedores tamb\u00e9m foram informados de que a opera\u00e7\u00e3o ser\u00e1 descontinuada.<\/p>\n\n\n\n<p>A empresa refor\u00e7ou que todas as compras feitas antes do fechamento ser\u00e3o mantidas normalmente. Os produtos j\u00e1 vendidos ser\u00e3o entregues e os pagamentos aos vendedores tamb\u00e9m ser\u00e3o realizados.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Por que a Elo7 foi encerrado<\/h2>\n\n\n\n<p>Segundo a Enjoei, a principal raz\u00e3o para o fechamento est\u00e1 na forte concorr\u00eancia do com\u00e9rcio. Grandes marketplaces internacionais, como a Shopee, cresceram muito no Brasil, o que aumentou os custos para atrair clientes e manter a plataforma ativa. No caso da Elo7, que atua em um nicho mais espec\u00edfico, ficou cada vez mais dif\u00edcil sustentar a opera\u00e7\u00e3o.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">O que a empresa pretende fazer agora<\/h2>\n\n\n\n<p>Com o fim da Elo7, a Enjoei pretende reorganizar os investimentos e concentra-los em outras \u00e1reas que tenham maior potencial de crescimento e retorno financeiro.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Enjoei anunciou o encerramento da Elo7, marketplace conhecido por reunir produtos artesanais feitos por pequenos vendedores. A decis\u00e3o foi divulgada nesta segunda-feira (11) e j\u00e1 come\u00e7ou a valer no mesmo dia. O site continua dispon\u00edvel, mas n\u00e3o permite mais novas compras. Os usu\u00e1rios podem at\u00e9 acessar os produtos, por\u00e9m n\u00e3o conseguem finalizar os pedidos. [&hellip;]<\/p>\n","protected":false},"author":17,"featured_media":27665,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":{"format":"standard"},"jnews_primary_category":[],"jnews_social_meta":[],"jnews_post_split":[],"footnotes":""},"categories":[1],"tags":[],"class_list":["post-27629","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/diariodepernambuco.audiencelabs.com.br\/wp-json\/wp\/v2\/posts\/27629","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diariodepernambuco.audiencelabs.com.br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diariodepernambuco.audiencelabs.com.br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diariodepernambuco.audiencelabs.com.br\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/diariodepernambuco.audiencelabs.com.br\/wp-json\/wp\/v2\/comments?post=27629"}],"version-history":[{"count":2,"href":"https:\/\/diariodepernambuco.audiencelabs.com.br\/wp-json\/wp\/v2\/posts\/27629\/revisions"}],"predecessor-version":[{"id":27666,"href":"https:\/\/diariodepernambuco.audiencelabs.com.br\/wp-json\/wp\/v2\/posts\/27629\/revisions\/27666"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diariodepernambuco.audiencelabs.com.br\/wp-json\/wp\/v2\/media\/27665"}],"wp:attachment":[{"href":"https:\/\/diariodepernambuco.audiencelabs.com.br\/wp-json\/wp\/v2\/media?parent=27629"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diariodepernambuco.audiencelabs.com.br\/wp-json\/wp\/v2\/categories?post=27629"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diariodepernambuco.audiencelabs.com.br\/wp-json\/wp\/v2\/tags?post=27629"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}