{"id":27778,"date":"2026-05-13T13:38:15","date_gmt":"2026-05-13T16:38:15","guid":{"rendered":"https:\/\/diariodepernambuco.audiencelabs.com.br\/?p=27778"},"modified":"2026-05-13T13:38:17","modified_gmt":"2026-05-13T16:38:17","slug":"definido-quem-sera-o-narrador-da-globo-na-copa-do-mundo","status":"publish","type":"post","link":"https:\/\/diariodepernambuco.audiencelabs.com.br\/definido-quem-sera-o-narrador-da-globo-na-copa-do-mundo\/","title":{"rendered":"Definido quem ser\u00e1 o narrador da Globo na Copa do Mundo"},"content":{"rendered":"\n<p>Faltando 29 dias para o come\u00e7o da Copa do Mundo, a Globo j\u00e1 definiu quais ser\u00e3o os narradores e equipes durantes as transmiss\u00f5es dos jogos da Sele\u00e7\u00e3o.<\/p>\n\n\n\n<p><strong>Everaldo Marques<\/strong> foi escolhido como narrador principal da equipe na Copa, assumindo o posto no lugar de Lu\u00eds Roberto, que est\u00e1 afastado por quest\u00f5es de sa\u00fade. Esta ser\u00e1 a segunda Copa de Everaldo na emissora. Tamb\u00e9m fazem parte do time de narra\u00e7\u00e3o nomes como Gustavo Villani e Renata Silveira.<\/p>\n\n\n\n<p>No time de comentaristas, a Globo ter\u00e1 Ana Tha\u00eds Matos, Cristiane Rozeira, Denilson e J\u00fanior.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Sportv<\/h2>\n\n\n\n<p>Segundo informa\u00e7\u00f5es do site <em>M\u00e1quina do Esporte<\/em>, na Sportv, a cobertura ser\u00e1 organizada com parte da equipe trabalhando diretamente nos pa\u00edses-sede e outra parte acompanhando tudo daqui do Brasil. A narra\u00e7\u00e3o dos jogos da Sele\u00e7\u00e3o ficar\u00e1 com Luiz Carlos Jr., que estar\u00e1 ao lado dos comentaristas Eric Faria e Ricardinho.<\/p>\n\n\n\n<p>Durante a fase de grupos, Dandan Pereira tamb\u00e9m participa da cobertura, enquanto Paulo Andrade assume as transmiss\u00f5es a partir das fases eliminat\u00f3rias.<\/p>\n\n\n\n<p>Do Brasil, a Sportv tamb\u00e9m ter\u00e1 um grupo grande de narradores, com Antero Neto, Isabelly Morais, Jader Rocha e Natalia Lara se revezando ao longo da competi\u00e7\u00e3o.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">GeTV<\/h2>\n\n\n\n<p>Na GeTV, a proposta \u00e9 uma transmiss\u00e3o com foco no digital e nas redes sociais. Ainda segundo o <em>M\u00e1quina do Esporte<\/em>, parte da equipe estar\u00e1 nos pa\u00edses-sede, acompanhando de perto treinos, bastidores e jogos, enquanto outra parte ficar\u00e1 no Brasil comentando tudo em tempo real.<\/p>\n\n\n\n<p>Entre os nomes no exterior est\u00e3o Mariana Spinelli, Sofia Miranda, Bruno Formiga e Fred Bruno, que v\u00e3o trazer conte\u00fados diretamente dos locais da Copa. J\u00e1 no Brasil, a cobertura fica com Jorge Iggor, Luana Maluf, Jordana Ara\u00fajo, Andr\u00e9 Balada e Rodrigo Capita.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Faltando 29 dias para o come\u00e7o da Copa do Mundo, a Globo j\u00e1 definiu quais ser\u00e3o os narradores e equipes durantes as transmiss\u00f5es dos jogos da Sele\u00e7\u00e3o. Everaldo Marques foi escolhido como narrador principal da equipe na Copa, assumindo o posto no lugar de Lu\u00eds Roberto, que est\u00e1 afastado por quest\u00f5es de sa\u00fade. Esta ser\u00e1 [&hellip;]<\/p>\n","protected":false},"author":17,"featured_media":17636,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":{"format":"standard"},"jnews_primary_category":[],"jnews_social_meta":[],"jnews_post_split":[],"footnotes":""},"categories":[1],"tags":[],"class_list":["post-27778","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/diariodepernambuco.audiencelabs.com.br\/wp-json\/wp\/v2\/posts\/27778","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diariodepernambuco.audiencelabs.com.br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diariodepernambuco.audiencelabs.com.br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diariodepernambuco.audiencelabs.com.br\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/diariodepernambuco.audiencelabs.com.br\/wp-json\/wp\/v2\/comments?post=27778"}],"version-history":[{"count":1,"href":"https:\/\/diariodepernambuco.audiencelabs.com.br\/wp-json\/wp\/v2\/posts\/27778\/revisions"}],"predecessor-version":[{"id":27789,"href":"https:\/\/diariodepernambuco.audiencelabs.com.br\/wp-json\/wp\/v2\/posts\/27778\/revisions\/27789"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diariodepernambuco.audiencelabs.com.br\/wp-json\/wp\/v2\/media\/17636"}],"wp:attachment":[{"href":"https:\/\/diariodepernambuco.audiencelabs.com.br\/wp-json\/wp\/v2\/media?parent=27778"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diariodepernambuco.audiencelabs.com.br\/wp-json\/wp\/v2\/categories?post=27778"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diariodepernambuco.audiencelabs.com.br\/wp-json\/wp\/v2\/tags?post=27778"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}